{"id":107,"date":"2025-11-24T13:49:23","date_gmt":"2025-11-24T12:49:23","guid":{"rendered":"https:\/\/www.turiongroup.com\/?page_id=107"},"modified":"2026-07-09T21:01:43","modified_gmt":"2026-07-09T20:01:43","slug":"politica-de-privacidad","status":"publish","type":"page","link":"https:\/\/www.turiongroup.com\/es\/politica-de-privacidad\/","title":{"rendered":"Pol\u00edtica de privacidad"},"content":{"rendered":"<style>.td-legal{max-width:none;width:100%;}.td-legal h1{font-size:2rem;line-height:1.2;margin:0 0 1.25rem;font-weight:700;}.td-legal h2{font-size:1.5rem;line-height:1.3;margin:2rem 0 .5rem;font-weight:700;}.td-legal h3{font-size:1.15rem;line-height:1.3;margin:1.5rem 0 .4rem;font-weight:700;}.td-legal p{margin:0 0 .85rem;line-height:1.6;}.td-legal ul{margin:0 0 1rem;}.td-legal a{text-decoration:underline;}.td-legal .td-cookie-group{font-weight:700;margin:1.5rem 0 .35rem;}.td-legal .td-table-wrap{overflow-x:auto;margin:.25rem 0 1.75rem;}.td-legal table{width:100%;border-collapse:collapse;min-width:560px;font-size:.95rem;}.td-legal th,.td-legal td{border:1px solid #d0d0d0;padding:.5rem .7rem;text-align:left;vertical-align:top;line-height:1.45;}.td-legal thead th{background:#ececec;font-weight:700;white-space:nowrap;}<\/style>\n<div class=\"td-legal\">\n<h1>POL\u00cdTICA DE PRIVACIDAD<\/h1>\n<h2>1. INFORMACI\u00d3N AL USUARIO<\/h2>\n<p>ESTURIONS DE COLORS SLU es el responsable del tratamiento de los datos personales del interesado y le informa de que estos datos se tratar\u00e1n de conformidad con lo dispuesto en el Reglamento (UE) 2016\/679, de 27 de abril (RGPD), y la Ley Org\u00e1nica 3\/2018, de 5 de diciembre (LOPDGDD), por lo que se le facilita la siguiente informaci\u00f3n del tratamiento:<\/p>\n<p>Fines del tratamiento: Dar respuesta a las consultas o cualquier tipo de peticio\u0301n que sea realizada por el usuario a trave\u0301s de cualquiera de las formas de contacto que se ponen a su disposicio\u0301n en la pa\u0301gina web del responsable (por el intere\u0301s legi\u0301timo del responsable, art. 6.1.f GDPR). Realizar ana\u0301lisis estadi\u0301sticos y estudios de mercado (por el intere\u0301s legi\u0301timo del responsable, art. 6.1.f GDPR)<\/p>\n<p>Legitimaci\u00f3n del tratamiento: Por un INTER\u00c9S LEG\u00cdTIMO del Responsable del tratamiento o Tercero (art\u00edculo 6.1.f GDPR)<\/p>\n<p>Criterios de conservaci\u00f3n de los datos: conservados durante no m\u00e1s tiempo del necesario para mantener el fin del tratamiento o mientras existan prescripciones legales que dictaminen su custodia<\/p>\n<p>Comunicaci\u00f3n de los datos: se informa de que no se comunican los datos a terceros, salvo por obligaci\u00f3n legal<\/p>\n<p>Fines del tratamiento: publicidad y prospecci\u00f3n comercial<\/p>\n<p>Legitimaci\u00f3n del tratamiento: CONSENTIMIENTO del interesado para fines espec\u00edficos (art\u00edculo 6.1.a GDPR)<\/p>\n<p>Criterios de conservaci\u00f3n de los datos: conservados durante no m\u00e1s tiempo del necesario para mantener el fin del tratamiento o mientras existan prescripciones legales que dictaminen su custodia<\/p>\n<p>Comunicaci\u00f3n de los datos: se informa de que no se comunican los datos a terceros, salvo por obligaci\u00f3n legal<\/p>\n<p>Transferencias internacionales de datos: SE INFORMA de que los datos pueden ser transferidos a pa\u00edses fuera del EEE mediante una DECISI\u00d3N DE ADECUACI\u00d3N de la Comisi\u00f3n Europea para la realizaci\u00f3n de comunicaciones comerciales con Mailchimp<\/p>\n<p>Derechos que asisten al interesado :<\/p>\n<p>Derecho a retirar el consentimiento en cualquier momento, cuando el tratamiento se base en el consentimiento del interesado.<\/p>\n<p>Derecho de acceso, rectificaci\u00f3n, portabilidad y supresi\u00f3n de sus datos y de limitaci\u00f3n u oposici\u00f3n a su tratamiento.<\/p>\n<p>Derecho a presentar una reclamaci\u00f3n ante la Autoridad de control (www.aepd.es) si considera que el tratamiento no se ajusta a la normativa vigente.<\/p>\n<p>Datos de contacto para ejercer sus derechos:<\/p>\n<p>ESTURIONS DE COLORS SLU C\/ Sallent, 61, &#8211; 08243 Manresa (Barcelona). E-mail: administracio@turiongroup.com<\/p>\n<h2>2. CAR\u00c1CTER OBLIGATORIO O FACULTATIVO DE LA INFORMACI\u00d3N FACILITADA POR EL USUARIO<\/h2>\n<p>Los USUARIOS, mediante la marcaci\u00f3n de las casillas correspondientes y la entrada de datos en los campos, marcados con un asterisco (*) en el formulario de contacto o presentados en formularios de descarga, aceptan expresamente y de forma libre e inequ\u00edvoca, que sus datos son necesarios para atender su petici\u00f3n, por parte del prestador, siendo voluntaria la inclusi\u00f3n de datos en los campos restantes. El USUARIO garantiza que los datos personales facilitados al RESPONSABLE son veraces y se hace responsable de comunicar cualquier modificaci\u00f3n de los mismos.<\/p>\n<p>El RESPONSABLE informa de que todos los datos solicitados a trav\u00e9s del sitio web son obligatorios, ya que son necesarios para la prestaci\u00f3n de un servicio \u00f3ptimo al USUARIO. En caso de que no se faciliten todos los datos, no se garantiza que la informaci\u00f3n y servicios facilitados sean completamente ajustados a sus necesidades.<\/p>\n<h2>3. MEDIDAS DE SEGURIDAD<\/h2>\n<p>Que de conformidad con lo dispuesto en las normativas vigentes en protecci\u00f3n de datos personales, el RESPONSABLE est\u00e1 cumpliendo con todas las disposiciones de las normativas RGPD y LOPDGDD para el tratamiento de los datos personales de su responsabilidad, y manifiestamente con los principios descritos en el art\u00edculo 5 del RGPD, por los cuales son tratados de manera l\u00edcita, leal y transparente en relaci\u00f3n con el interesado y adecuados, pertinentes y limitados a lo necesario en relaci\u00f3n con los fines para los que son tratados.<\/p>\n<p>El RESPONSABLE garantiza que ha implementado pol\u00edticas t\u00e9cnicas y organizativas apropiadas para aplicar las medidas de seguridad que establecen el RGPD y la LOPDGDD con el fin de proteger los derechos y libertades de los USUARIOS y les ha comunicado la informaci\u00f3n adecuada para que puedan ejercerlos.<\/p>\n<p>Para m\u00e1s informaci\u00f3n sobre las garant\u00edas de privacidad, puedes dirigirte al RESPONSABLE a trav\u00e9s de ESTURIONS DE COLORS SLU. C\/ Sallent, 61, &#8211; 08243 Manresa (Barcelona). E-mail: administracio@turiongroup.com<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>POL\u00cdTICA DE PRIVACIDAD 1. INFORMACI\u00d3N AL USUARIO ESTURIONS DE COLORS SLU es el responsable del tratamiento de los datos personales del interesado y le informa de que estos datos se tratar\u00e1n de conformidad con lo dispuesto en el Reglamento (UE) 2016\/679, de 27 de abril (RGPD), y la Ley Org\u00e1nica 3\/2018, de 5 de diciembre&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-107","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.turiongroup.com\/es\/wp-json\/wp\/v2\/pages\/107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.turiongroup.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.turiongroup.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.turiongroup.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.turiongroup.com\/es\/wp-json\/wp\/v2\/comments?post=107"}],"version-history":[{"count":8,"href":"https:\/\/www.turiongroup.com\/es\/wp-json\/wp\/v2\/pages\/107\/revisions"}],"predecessor-version":[{"id":2007,"href":"https:\/\/www.turiongroup.com\/es\/wp-json\/wp\/v2\/pages\/107\/revisions\/2007"}],"wp:attachment":[{"href":"https:\/\/www.turiongroup.com\/es\/wp-json\/wp\/v2\/media?parent=107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}